{"id":173758,"date":"2025-12-23T11:28:38","date_gmt":"2025-12-23T02:28:38","guid":{"rendered":"https:\/\/www.leafkyoto.net\/?post_type=mall&#038;p=173758"},"modified":"2026-04-27T17:48:17","modified_gmt":"2026-04-27T08:48:17","slug":"251217-assemblageclub-1","status":"publish","type":"mall","link":"https:\/\/www.leafkyoto.net\/en\/mall\/251217-assemblageclub-1\/","title":{"rendered":"Assemblage Club 05 Kasumi &#8211; \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 &#8211;"},"content":{"rendered":"<p>\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi &#8211; \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002<\/p>","protected":false},"author":56,"featured_media":173759,"template":"","tags":[],"mall_tag":[],"mall_category":[869,873],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 - \u306e\u901a\u8ca9 | Leaf \u53b3\u9078 \u4eac\u90fd\u30b0\u30eb\u30e1\u306e\u304a\u53d6\u308a\u5bc4\u305b \uff5eLeaf KYOTO mall\uff5e<\/title>\n<meta name=\"description\" content=\"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leafkyoto.net\/en\/mall\/251217-assemblageclub-1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assemblage Club 05 Kasumi - \u67d1\u6f84 - 2025\" \/>\n<meta property=\"og:description\" content=\"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leafkyoto.net\/en\/mall\/251217-assemblageclub-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Leaf KYOTO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leafkyoto\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T08:48:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2025\/12\/251216-kasumi1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Assemblage Club 05 Kasumi - \u67d1\u6f84 - 2025\" \/>\n<meta name=\"twitter:description\" content=\"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2025\/12\/251216-kasumi1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/\",\"url\":\"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/\",\"name\":\"Assemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 - \u306e\u901a\u8ca9 | Leaf \u53b3\u9078 \u4eac\u90fd\u30b0\u30eb\u30e1\u306e\u304a\u53d6\u308a\u5bc4\u305b \uff5eLeaf KYOTO mall\uff5e\",\"isPartOf\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#website\"},\"datePublished\":\"2025-12-23T02:28:38+00:00\",\"dateModified\":\"2026-04-27T08:48:17+00:00\",\"description\":\"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leaf KYOTO\",\"item\":\"https:\/\/www.leafkyoto.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mall\u5546\u54c1\",\"item\":\"https:\/\/www.leafkyoto.net\/mall\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assemblage Club 05 Kasumi &#8211; \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 &#8211;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leafkyoto.net\/#website\",\"url\":\"https:\/\/www.leafkyoto.net\/\",\"name\":\"Leaf KYOTO\u3000\u4eac\u90fd\u30b0\u30eb\u30e1\uff06\u304a\u3067\u304b\u3051\u60c5\u5831\",\"description\":\"\u4eac\u90fd\u306e\u5730\u5143\u60c5\u5831\u3092\u304a\u5c4a\u3051\uff01\",\"publisher\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#organization\"},\"alternateName\":\"Leaf KYOTO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leafkyoto.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leafkyoto.net\/#organization\",\"name\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\",\"url\":\"https:\/\/www.leafkyoto.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg\",\"contentUrl\":\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\"},\"image\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/leafkyoto\/\",\"https:\/\/x.com\/leafkyoto\/\",\"https:\/\/www.instagram.com\/leaf_kyoto\/\",\"https:\/\/www.threads.net\/@leaf_kyoto\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 - \u306e\u901a\u8ca9 | Leaf \u53b3\u9078 \u4eac\u90fd\u30b0\u30eb\u30e1\u306e\u304a\u53d6\u308a\u5bc4\u305b \uff5eLeaf KYOTO mall\uff5e","description":"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leafkyoto.net\/en\/mall\/251217-assemblageclub-1\/","og_locale":"en_US","og_type":"article","og_title":"Assemblage Club 05 Kasumi - \u67d1\u6f84 - 2025","og_description":"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002","og_url":"https:\/\/www.leafkyoto.net\/en\/mall\/251217-assemblageclub-1\/","og_site_name":"Leaf KYOTO","article_publisher":"https:\/\/www.facebook.com\/leafkyoto\/","article_modified_time":"2026-04-27T08:48:17+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2025\/12\/251216-kasumi1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Assemblage Club 05 Kasumi - \u67d1\u6f84 - 2025","twitter_description":"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002","twitter_image":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2025\/12\/251216-kasumi1.jpg","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/","url":"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/","name":"Assemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 - \u306e\u901a\u8ca9 | Leaf \u53b3\u9078 \u4eac\u90fd\u30b0\u30eb\u30e1\u306e\u304a\u53d6\u308a\u5bc4\u305b \uff5eLeaf KYOTO mall\uff5e","isPartOf":{"@id":"https:\/\/www.leafkyoto.net\/#website"},"datePublished":"2025-12-23T02:28:38+00:00","dateModified":"2026-04-27T08:48:17+00:00","description":"\u4eac\u90fd\u306e\u9152\u85353\u8535\u306e\u57a3\u6839\u3092\u8d85\u3048\u305f\u300c\u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u300d\u306b\u3088\u3063\u3066\u8a95\u751f\u3057\u305fAssemblage Club 05 Kasumi - \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 -\u3002 \u30a2\u30c3\u30b5\u30f3\u30d6\u30e9\u30fc\u30b8\u30e5\u3068\u306f\u6df7\u305c\u5408\u308f\u305b\u3092\u610f\u5473\u3059\u308b\u30d5\u30e9\u30f3\u30b9\u8a9e\u3067\u3001\u30ef\u30a4\u30f3\u3084\u30b7\u30e3\u30f3\u30d1\u30fc\u30cb\u30e5\u9020\u308a\u306e\u904e\u7a0b\u3067\u4f1d\u7d71\u7684\u306b\u884c\u308f\u308c\u308b\u30d6\u30ec\u30f3\u30c9\u6280\u6cd5\u306e\u3053\u3068\u3002Kasumi\uff08\u67d1\u6f84\uff09\u306f\u7518\u9178\u3063\u3071\u304f\u30af\u30ea\u30a2\u306a\u5589\u8d8a\u3057\u306e\u30e9\u30a4\u30c8\u30c6\u30a4\u30b9\u30c8\u65e5\u672c\u9152\u3067\u3001\u6599\u7406\u306e\u98a8\u5473\u3092\u90aa\u9b54\u3057\u306a\u3044\u201c\u30cb\u30e5\u30fc\u30c8\u30e9\u30eb\u306a\u5473\u308f\u3044\u201d\u3068\u3057\u3066\u3069\u3093\u306a\u98df\u306b\u3082\u5bc4\u308a\u6dfb\u3046\u306e\u304c\u7279\u5fb4\u3002\u900f\u660e\u611f\u306e\u3042\u308b\u3046\u307e\u5473\u306f\u3001\u9b5a\u4ecb\u6599\u7406\u306f\u3082\u3061\u308d\u3093\u3001\u98df\u524d\u9152\u3084\u30ef\u30a4\u30f3\u306b\u4ee3\u308f\u308b\u300c\u65b0\u30fb\u98df\u4e2d\u9152\u300d\u3068\u3057\u3066\u3082\u304a\u3059\u3059\u3081\u3060\u3002","breadcrumb":{"@id":"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leafkyoto.net\/mall\/251217-assemblageclub-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leaf KYOTO","item":"https:\/\/www.leafkyoto.net\/"},{"@type":"ListItem","position":2,"name":"mall\u5546\u54c1","item":"https:\/\/www.leafkyoto.net\/mall\/"},{"@type":"ListItem","position":3,"name":"Assemblage Club 05 Kasumi &#8211; \u67d1\u6f84\uff08\u304b\u3059\u307f\uff09 &#8211;"}]},{"@type":"WebSite","@id":"https:\/\/www.leafkyoto.net\/#website","url":"https:\/\/www.leafkyoto.net\/","name":"Leaf KYOTO\u3000\u4eac\u90fd\u30b0\u30eb\u30e1\uff06\u304a\u3067\u304b\u3051\u60c5\u5831","description":"\u4eac\u90fd\u306e\u5730\u5143\u60c5\u5831\u3092\u304a\u5c4a\u3051\uff01","publisher":{"@id":"https:\/\/www.leafkyoto.net\/#organization"},"alternateName":"Leaf KYOTO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leafkyoto.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leafkyoto.net\/#organization","name":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba","url":"https:\/\/www.leafkyoto.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg","contentUrl":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg","width":1000,"height":1000,"caption":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba"},"image":{"@id":"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leafkyoto\/","https:\/\/x.com\/leafkyoto\/","https:\/\/www.instagram.com\/leaf_kyoto\/","https:\/\/www.threads.net\/@leaf_kyoto"]}]}},"_links":{"self":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/mall\/173758"}],"collection":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/mall"}],"about":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/types\/mall"}],"author":[{"embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/users\/56"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/media\/173759"}],"wp:attachment":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/media?parent=173758"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/tags?post=173758"},{"taxonomy":"mall_tag","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/mall_tag?post=173758"},{"taxonomy":"mall_category","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/mall_category?post=173758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}