{"id":48806,"date":"2023-05-27T10:00:25","date_gmt":"2023-05-27T01:00:25","guid":{"rendered":"https:\/\/www.leafkyoto.net\/?post_type=event&#038;p=48806"},"modified":"2023-05-24T12:12:48","modified_gmt":"2023-05-24T03:12:48","slug":"230522-kyoto-wadamakototen","status":"publish","type":"event","link":"https:\/\/www.leafkyoto.net\/en\/events\/230522-kyoto-wadamakototen\/","title":{"rendered":"Makoto Wada Exhibition\" - \"You may know it, but you didn't know it\" \/ Museum \"Eki\" KYOTO"},"content":{"rendered":"","protected":false},"author":42,"featured_media":49967,"template":"","categories":[1],"tags":[566],"tourism":[185],"areas":[522],"genre":[],"scene":[],"sftag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO | Leaf KYOTO<\/title>\n<meta name=\"description\" content=\"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leafkyoto.net\/en\/events\/230522-kyoto-wadamakototen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO\" \/>\n<meta property=\"og:description\" content=\"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leafkyoto.net\/en\/events\/230522-kyoto-wadamakototen\/\" \/>\n<meta property=\"og:site_name\" content=\"Leaf KYOTO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leafkyoto\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T03:12:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2023\/05\/230522-wadamakototen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO\" \/>\n<meta name=\"twitter:description\" content=\"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2023\/05\/230522-wadamakototen.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/\",\"url\":\"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/\",\"name\":\"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO | Leaf KYOTO\",\"isPartOf\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#website\"},\"datePublished\":\"2023-05-27T01:00:25+00:00\",\"dateModified\":\"2023-05-24T03:12:48+00:00\",\"description\":\"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leaf KYOTO\",\"item\":\"https:\/\/www.leafkyoto.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u30a4\u30d9\u30f3\u30c8\",\"item\":\"https:\/\/www.leafkyoto.net\/event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leafkyoto.net\/#website\",\"url\":\"https:\/\/www.leafkyoto.net\/\",\"name\":\"Leaf KYOTO\u3000\u4eac\u90fd\u30b0\u30eb\u30e1\uff06\u304a\u3067\u304b\u3051\u60c5\u5831\",\"description\":\"\u4eac\u90fd\u306e\u5730\u5143\u60c5\u5831\u3092\u304a\u5c4a\u3051\uff01\",\"publisher\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#organization\"},\"alternateName\":\"Leaf KYOTO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leafkyoto.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.leafkyoto.net\/#organization\",\"name\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\",\"url\":\"https:\/\/www.leafkyoto.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg\",\"contentUrl\":\"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\"},\"image\":{\"@id\":\"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/leafkyoto\/\",\"https:\/\/x.com\/leafkyoto\/\",\"https:\/\/www.instagram.com\/leaf_kyoto\/\",\"https:\/\/www.threads.net\/@leaf_kyoto\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO | Leaf KYOTO","description":"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leafkyoto.net\/en\/events\/230522-kyoto-wadamakototen\/","og_locale":"en_US","og_type":"article","og_title":"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO","og_description":"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002","og_url":"https:\/\/www.leafkyoto.net\/en\/events\/230522-kyoto-wadamakototen\/","og_site_name":"Leaf KYOTO","article_publisher":"https:\/\/www.facebook.com\/leafkyoto\/","article_modified_time":"2023-05-24T03:12:48+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2023\/05\/230522-wadamakototen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO","twitter_description":"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002","twitter_image":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2023\/05\/230522-wadamakototen.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/","url":"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/","name":"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO | Leaf KYOTO","isPartOf":{"@id":"https:\/\/www.leafkyoto.net\/#website"},"datePublished":"2023-05-27T01:00:25+00:00","dateModified":"2023-05-24T03:12:48+00:00","description":"2023\u5e746\u670818\u65e5\uff08\u65e5\uff09\u307e\u3067\u306e\u671f\u9593\u3001JR\u4eac\u90fd\u99c5\u30d3\u30eb\u4f75\u8a2d\u306e\uff3b\u7f8e\u8853\u9928\u300c\u3048\u304d\u300dKYOTO\uff3d\u306b\u3066\u3001\u300e\u548c\u7530\u8aa0\u5c55\u300f\u304c\u958b\u50ac\u3055\u308c\u3066\u3044\u308b\u3002","breadcrumb":{"@id":"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leafkyoto.net\/event\/230522-kyoto-wadamakototen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leaf KYOTO","item":"https:\/\/www.leafkyoto.net\/"},{"@type":"ListItem","position":2,"name":"\u30a4\u30d9\u30f3\u30c8","item":"https:\/\/www.leafkyoto.net\/event\/"},{"@type":"ListItem","position":3,"name":"\u77e5\u3063\u3066\u308b\u3088\u3046\u3067\u77e5\u3089\u306a\u304b\u3063\u305f\u30fc\u3042\u308c\u3082\u3053\u308c\u3082\u305d\u308c\u3082\u300e\u548c\u7530\u8aa0\u5c55\u300f\uff0f\u7f8e\u8853\u9928\u300c\u3048\u304d\u300d KYOTO"}]},{"@type":"WebSite","@id":"https:\/\/www.leafkyoto.net\/#website","url":"https:\/\/www.leafkyoto.net\/","name":"Leaf KYOTO\u3000\u4eac\u90fd\u30b0\u30eb\u30e1\uff06\u304a\u3067\u304b\u3051\u60c5\u5831","description":"\u4eac\u90fd\u306e\u5730\u5143\u60c5\u5831\u3092\u304a\u5c4a\u3051\uff01","publisher":{"@id":"https:\/\/www.leafkyoto.net\/#organization"},"alternateName":"Leaf KYOTO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leafkyoto.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.leafkyoto.net\/#organization","name":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba","url":"https:\/\/www.leafkyoto.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg","contentUrl":"https:\/\/www.leafkyoto.net\/leaf\/wp-content\/uploads\/2024\/11\/logo.jpg","width":1000,"height":1000,"caption":"\u682a\u5f0f\u4f1a\u793e\u30ea\u30fc\u30d5\u30fb\u30d1\u30d6\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba"},"image":{"@id":"https:\/\/www.leafkyoto.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leafkyoto\/","https:\/\/x.com\/leafkyoto\/","https:\/\/www.instagram.com\/leaf_kyoto\/","https:\/\/www.threads.net\/@leaf_kyoto"]}]}},"_links":{"self":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/event\/48806"}],"collection":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/users\/42"}],"version-history":[{"count":0,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/event\/48806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/media\/49967"}],"wp:attachment":[{"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/media?parent=48806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/categories?post=48806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/tags?post=48806"},{"taxonomy":"tourism","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/tourism?post=48806"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/areas?post=48806"},{"taxonomy":"genre","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/genre?post=48806"},{"taxonomy":"scene","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/scene?post=48806"},{"taxonomy":"sftag","embeddable":true,"href":"https:\/\/www.leafkyoto.net\/en\/wp-json\/wp\/v2\/sftag?post=48806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}